{"id":8016,"date":"2023-05-13T08:00:24","date_gmt":"2023-05-13T06:00:24","guid":{"rendered":"https:\/\/acidmoto.ch\/site\/?p=8016"},"modified":"2024-03-16T02:44:00","modified_gmt":"2024-03-16T01:44:00","slug":"essai-kawasaki-z900-se-2022-le-compromis-ideal","status":"publish","type":"post","link":"https:\/\/acidmoto.ch\/site\/essai-kawasaki-z900-se-2022-le-compromis-ideal\/","title":{"rendered":"Essai Kawasaki Z900 SE 2022 &#8211; Le compromis id\u00e9al"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2>Prenez un des best-seller de Kawasaki, greffez-lui des suspensions Ohlins et des freins Brembo\u00a0: vous obtenez la Z900 SE (Suspension Edition). Mais ces ajustements sont-ils n\u00e9cessaires sur une base d\u00e9j\u00e0 saine ?<\/h2>\n<h2>Tentatives de r\u00e9ponses<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=\u00a0\u00bbessai\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>ESSAI<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text]La Kawasaki Z900, c&rsquo;est d\u00e9j\u00e0 une recette qui a fait ses preuves. Avec sa partie cycle plut\u00f4t sportive sans n\u00e9gliger le confort, son excellente maniabilit\u00e9, un 4 cylindres simple et dot\u00e9 d\u2019une bonne sonorit\u00e9, elle tient d\u00e9j\u00e0 bien son rang parmi les machines fiables et efficaces de la marque. Et d\u00e9sormais, si vous cherchez quelque chose d&rsquo;un peu plus pointu, le constructeur japonais vous propose la version SE. Et qu&rsquo;est ce qu\u2019on y gagne, me demanderez-vous?[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag -->\n            <ins data-revive-zoneid=\"54\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Et bien concr\u00e8tement, des suspensions de haute qualit\u00e9 enti\u00e8rement r\u00e9glables ainsi qu&rsquo;un excellent freinage Brembo (des M4.32 pour les connaisseurs). Ces \u00e9quipements peuvent s&rsquo;av\u00e9rer tr\u00e8s int\u00e9ressants pour quelqu&rsquo;un qui voudrait s&rsquo;initier \u00e0 la piste par exemple, mais nous y reviendrons.[\/vc_column_text][vc_single_image image=\u00a0\u00bb8042&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Le moteur<\/h3>\n<p>Comme c\u2019est souvent le cas avec les 4 cylindres japonais, le moteur a la qualit\u00e9 de ses d\u00e9fauts. Oui, comprenez bien. Vous ne pouvez pas avoir \u00e0 la fois un moteur ultra lin\u00e9aire et tr\u00e8s coupleux, de m\u00eame que vous ne pouvez pas obtenir un caract\u00e8re moteur extraordinaire tout en gardant des vibrations moteur tr\u00e8s limit\u00e9es. Finalement, le moteur de la Z900 c&rsquo;est une histoire de compromis\u00a0: coupleux mais pas trop, d\u00e9monstratif sans exag\u00e9ration et avec une production tr\u00e8s limit\u00e9e de vibrations parasites.<\/p>\n<p>Hop, d\u00e8s que le moteur se met \u00e0 tourner, une sonorit\u00e9 enivrante me donne aussit\u00f4t envie de prendre la route et de partir \u00e0 la recherche de trac\u00e9s sinueux. Premi\u00e8re surprise au guidon : le moteur \u00ab\u00a0tire plut\u00f4t court\u00a0\u00bb pour un 4 cylindres. Sa zone rouge \u00e0 11&rsquo;000 trs\/min me force \u00e0 jouer r\u00e9guli\u00e8rement de la bo\u00eete de vitesses (ce qui n\u2019est pas forc\u00e9ment un d\u00e9faut d&rsquo;un point de vue motard). En ville, on appr\u00e9ciera sans aucun doute la souplesse de ce moteur ainsi que sa facilit\u00e9 de prise en main. Toujours pour une conduite citadine, l\u2019embrayage Assist&amp;Slipper s\u2019av\u00e8re tr\u00e8s agr\u00e9able, puisqu\u2019il suffit d\u2019une tr\u00e8s faible pression sur le levier pour l\u2019actionner. Sur routes sinueuses, l\u2019avantage est que l\u2019on peut se concentrer sur ses trajectoires, car contrairement \u00e0 d&rsquo;autres motos plus caract\u00e9rielles, la Z900 ne demande pas un gros bagage d&rsquo;exp\u00e9rience pour l&rsquo;apprivoiser. Bon, comme souvent avec les 4 cylindres japonais, il y a ses adorateurs et ses d\u00e9tracteurs et cette Z 900 SE ne d\u00e9roge pas \u00e0 la r\u00e8gle. Pour autant, n\u2019allez pas croire que ce moteur ne vous offrira pas assez de performance pour rouler tous les jours, car il s\u2019agit tout de m\u00eame d\u2019un 4 cylindres en ligne de 948 cm3.[\/vc_column_text][vc_single_image image=\u00a0\u00bb8040&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bblink_image\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag -->\n            <ins data-revive-zoneid=\"56\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text]En r\u00e9alit\u00e9, selon moi le moteur se rapproche plus du comportement d\u2019un mille cm3 que d\u2019un mid-size. Point sympathique \u00e0 signaler \u00e9galement, le bruit d\u2019admission, renforc\u00e9 par la bo\u00eete \u00e0 air situ\u00e9e juste devant le pilote. On regrettera l\u2019absence de shifter d\u2019origine sur la version SE. Etonnant pour une moto qui se veut \u00e0 la pointe de la gamme de la marque ![\/vc_column_text][vc_column_text]<\/p>\n<h3>Autonomie<\/h3>\n<p>Je tournais \u00e0 environ 6 litres\/100 kilom\u00e8tres lors de mon essai. Comptez, pour \u00eatre large, 250 kilom\u00e8tres d\u2019autonomie. Un chiffre plut\u00f4t satisfaisant pour une moto de cette cat\u00e9gorie.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb8034&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb8018&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag - Desktop -->\n            <ins data-revive-zoneid=\"55\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb parallax_image=\u00a0\u00bb8023&Prime; el_id=\u00a0\u00bbImage Parallaxe\u00a0\u00bb][vc_column parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb600px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Partie cycle<\/h3>\n<p>Malgr\u00e9 un poids relativement \u00e9lev\u00e9 compar\u00e9 \u00e0 celui de ses concurrentes, cette Kawasaki offre une maniabilit\u00e9 exceptionnelle qui la rendrait presque d\u00e9routante. Tout semble si facile ! Le moteur a beau se rapprocher d\u2019une grosse cylindr\u00e9e, il ne faut pas se laisser impressionner. La partie cycle rend la conduite tout \u00e0 fait accessible. Une fois que vous amorcez le virage, la machine suivra fid\u00e8lement et sans vaciller la ligne que vous tracez. Et son poids, justement, participe \u00e0 cet effet de stabilit\u00e9.<\/p>\n<p>La principale diff\u00e9rence entre la version standard et celle SE se trouve au niveau de l\u2019amortisseur arri\u00e8re. Sur la SE, on trouve en effet un Ohlins S46 r\u00e9glable en d\u00e9tente et en pr\u00e9charge. Je ne peux que vous conseiller de regarder au pr\u00e9alable avec votre garagiste afin de <a href=\"https:\/\/acidmoto.ch\/site\/comment-bien-regler-ses-suspensions-guide-pour-comprendre-avant-de-toucher\/\">r\u00e9gler cet amortisseur en fonction de votre gabarit<\/a>, \u00e9tant donn\u00e9 que comme pour toute moto sortant d\u2019usine, les r\u00e9glages de base ne seront pas forc\u00e9ment adapt\u00e9s \u00e0 votre silhouette. Et une fois le r\u00e9glage fait, on peut parler d\u2019un atout non n\u00e9gligeable. A propos de gabarit, petit d\u00e9tail, je mesure 192 cm et mes deux pieds touchent naturellement bien le sol, mais j\u2019aurais pr\u00e9f\u00e9r\u00e9 personnellement une hauteur de selle un poil plus \u00e9lev\u00e9e.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"lipsum\">\n<p>Pour qui veut encha\u00eener les kilom\u00e8tres, cat\u00e9gorie des roadsters oblige, le confort de la moto reste limit\u00e9, bien que satisfaisant pour un tour d\u2019une \u00e0 deux heures maximum. Gare au mal de fesses en revanche pour votre \u00e9ventuel complice, car la selle passager est particuli\u00e8rement rude. Pas l\u2019id\u00e9al, donc, pour une balade en duo.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=\u00a0\u00bb8022&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Freinage<\/h3>\n<p>Comme sur la plupart des motos modernes, le freinage \u00e9tait d\u00e9j\u00e0 performant sur la version Z900 standard et il passe \u00e0 un niveau suppl\u00e9mentaire gr\u00e2ce aux \u00e9triers M4.32 Brembo. Autrement dit, plus que satisfaisant pour un usage routier et parfait pour un usage sur piste. Ajoutons que les durites de frein tress\u00e9es apportent un suppl\u00e9ment de mordant au feeling du frein avant. Je trouve toujours agr\u00e9able de n\u2019avoir que peu de soucis \u00e0 se faire quant aux capacit\u00e9s de freinage. Tr\u00e8s rassurant, donc\u00a0![\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=\u00a0\u00bb8057&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb content_placement=\u00a0\u00bbtop\u00a0\u00bb parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb parallax_image=\u00a0\u00bb8050&Prime;][vc_column][vc_empty_space height=\u00a0\u00bb600px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Conclusion<\/h3>\n<p>La Z900 SE est une am\u00e9lioration d\u2019une moto d\u00e9j\u00e0 r\u00e9ussie. Depuis la disparition du catalogue de la Z1000, on peut dire que la 900 est sa digne h\u00e9riti\u00e8re et que la SE vient compl\u00e9ter la gamme \u00e0 la mani\u00e8re d\u2019une Z1000 R de l\u2019\u00e9poque.<\/p>\n<p>Je vous conseillerais d\u2019opter pour cette version si vous souhaitez d\u00e9couvrir la piste au guidon de cette machine. La Z900 SE est toute indiqu\u00e9e aussi, il faut bien l\u2019avouer, si vous \u00eates amateur de belles pi\u00e8ces. Dans les autres cas, la version classique suffira. Perso, j\u2019aurais appr\u00e9ci\u00e9 une moto un peu plus caract\u00e9rielle, mais force est de constater que cette moto diablement efficace satisfera la majorit\u00e9 d\u2019entre vous.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=\u00a0\u00bbgal\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>GALERIE<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid style=\u00a0\u00bbload-more\u00a0\u00bb items_per_page=\u00a0\u00bb12&Prime; element_width=\u00a0\u00bb2&Prime; btn_color=\u00a0\u00bbdefault\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1683996449455-2d1a7b76-1734-1&Prime; include=\u00a0\u00bb8060,8059,8058,8057,8056,8055,8054,8053,8052,8051,8050,8049,8048,8047,8046,8045,8032,8031,8030,8029,8028,8027,8026,8025,8024,8023,8022,8021,8020,8019,8018,8017,8044,8043,8042,8041,8040,8039,8038,8037,8036,8035,8034,8033&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Prenez un des best-seller de Kawasaki, greffez-lui des suspensions Ohlins et des freins Brembo\u00a0: vous obtenez la Z900 SE (Suspension Edition). Mais ces ajustements sont-ils n\u00e9cessaires sur une base d\u00e9j\u00e0 saine ?<\/p>\n","protected":false},"author":4,"featured_media":8054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17,57],"tags":[461,311],"class_list":["post-8016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essais","category-roadster","tag-461","tag-roadster","xg_marques-kawasaki"],"_links":{"self":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/8016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/comments?post=8016"}],"version-history":[{"count":4,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/8016\/revisions"}],"predecessor-version":[{"id":8066,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/8016\/revisions\/8066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/media\/8054"}],"wp:attachment":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/media?parent=8016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/categories?post=8016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/tags?post=8016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}