{"id":2511,"date":"2018-04-15T08:00:56","date_gmt":"2018-04-15T06:00:56","guid":{"rendered":"https:\/\/acidmoto.ch\/site\/?p=2511"},"modified":"2024-03-16T02:44:28","modified_gmt":"2024-03-16T01:44:28","slug":"homologation-des-silencieux-dechappement-en-suisse-attention-aux-mauvaises-surprises-si-certificat-ce","status":"publish","type":"post","link":"https:\/\/acidmoto.ch\/site\/homologation-des-silencieux-dechappement-en-suisse-attention-aux-mauvaises-surprises-si-certificat-ce\/","title":{"rendered":"Homologation des silencieux &#8211; Attention aux mauvaises surprises si certificat CE !"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2>S\u2019il y a bien un sujet qui revient continuellement sur les r\u00e9seaux sociaux, c\u2019est celui de l\u2019homologation des syst\u00e8mes d\u2019\u00e9chappements pour la Suisse. Car oui, la Suisse ne fait toujours pas partie de l\u2019Europe, enfin si, mais non, que g\u00e9ographiquement en fait, ce qui en fait une petite omerta avec ses propres r\u00e8gles en mati\u00e8res de circulation routi\u00e8re et d\u2019homologation de certains de produits.<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=\u00a0\u00bbTutoriel\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>TUTORIEL<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text]D\u2019o\u00f9 parfois, certaines incompr\u00e9hensions ou malentendus voire sentiments d\u2019injustice par rapport \u00e0 nos voisins europ\u00e9ens. Oui, vous savez, ceux qui b\u00e9n\u00e9ficient d\u2019un seul et m\u00eame r\u00e8glement pour l\u2019ensemble des pi\u00e8ces qui sont vendues sur ce Vieux Continent, le fameux \u00ab\u00a0CE\u00a0\u00bb que nous trouvons \u00e9galement par chez nous, puisque la grande partie des produits pour deux-roues motoris\u00e9s\u00a0provient d&rsquo;Europe.<\/p>\n<p>Alors soucieux de pouvoir vous donner une information la plus juste qui soit et afin de faire taire les bruits de couloir, de l\u2019oncle, du cousin, de la soeur, de la tante, de la grand-m\u00e8re et du voisin\u2026, nous avons questionn\u00e9 les autorit\u00e9s comp\u00e9tentes de tous les cantons romands, \u00e0 savoir les bureaux des automobiles.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag -->\n            <ins data-revive-zoneid=\"54\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid element_width=\u00a0\u00bb3&Prime; grid_id=\u00a0\u00bbvc_gid:1660552917579-72059f86-7b71-4&Prime; include=\u00a0\u00bb2512,2513,2514,2515&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Pour les cantons qui ont pris la peine de nous r\u00e9pondre, nous remercions d\u00e9j\u00e0 le canton du Jura, du Valais, de Gen\u00e8ve et Vaud qui nous ont fourni des r\u00e9ponses pr\u00e9cises et donc sans ambigu\u00eft\u00e9 possible.<\/p>\n<p>Notre question \u00e9tait plut\u00f4t simple, puisque nous avons simplement pr\u00e9sent\u00e9 plusieurs certificats d\u2019homologation \u00ab CE \u00bb aux diff\u00e9rents bureaux des automobiles et avons attendu patiemment leurs r\u00e9ponses.<\/p>\n<p>Il faut savoir que les inspecteurs des services comp\u00e9tents se basent tous et sans exception sur les directives de l\u2019OFROU \u00ab\u00a0Office F\u00e9d\u00e9rale des Routes\u00a0\u00bb, ainsi que sur l\u2019ASA \u00ab\u00a0Association Suisse des Automobiles\u00a0\u00bb qui dispensent les cours afin de pouvoir devenir inspecteur.<\/p>\n<p>Et la r\u00e9ponse ne s&rsquo;est pas faite\u00a0attendre, puisque les 4 certificats que nous avons pr\u00e9sent\u00e9s, ne r\u00e9pondaient pas aux directives pour pouvoir obtenir le pr\u00e9cieux certificats \u00ab\u00a0CH\u00a0\u00bb.[\/vc_column_text][vc_single_image image=\u00a0\u00bb2516&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bblink_image\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Comme vous l&rsquo;aurez peut-\u00eatre remarqu\u00e9, sur les homologations CE, il manque des \u00e9l\u00e9ments, tels que la r\u00e9ception par type suisse (impossible \u00e0 obtenir hors de suisse), la puissance nominale avec son r\u00e9gime.<\/p>\n<p>Des \u00e9l\u00e9ments qui font que votre \u00e9chappement ne sera pas reconnu par les autorit\u00e9s, que ce soit de contr\u00f4le (bureau des automobiles) ou des diff\u00e9rents services de Police (quoique certains sont plut\u00f4t tol\u00e9rant, mais ne le prenez pas pour un acquis).<\/p>\n<p>Ensuite, il faut \u00e9galement savoir ce que vous risquez en cas de circulation ou de passage de visite sans votre pr\u00e9cieuse homologation CH.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag -->\n            <ins data-revive-zoneid=\"56\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text]<\/p>\n<h3>Bon, je n&rsquo;ai pas de certificat CH, mais je suis un rebelle et je prends le risque. Ok, mais je risque quoi en fait ?<\/h3>\n<h4>La visite technique :<\/h4>\n<p>La fameuse visite au bureau des automobiles. Celle qui fait trembler dans les chaumi\u00e8res et qui fait perdre son temps et son argent pour rien si vous n&rsquo;\u00eates pas titulaire du certificat d&rsquo;homologation CH.<br \/>\nBinh au final, de par le fait que le bureau des automobiles est uniquement un organe de contr\u00f4le lors d&rsquo;une visite, vous ne risquerez pas grand-chose, si ce n&rsquo;est de devoir vous pr\u00e9senter \u00e0 une nouvelle visite. Donc, de devoir payer \u00e0 nouveau des frais, mais surtout de ne pas voir votre permis de circulation \u00eatre \u00e0 jour.<\/p>\n<h4>Le contr\u00f4le de Police :<\/h4>\n<p>Ouhhhh&#8230; L\u00e0 j&rsquo;en entends d\u00e9j\u00e0 certains crier aux scandales, se plaindre \u00e0 tout va et j&rsquo;en passe. N&rsquo;oubliez pas juste une chose, ces personnes font leur m\u00e9tier, tout comme les inspecteurs, de ce fait, si vous connaissez les r\u00e8gles, \u00e0 vous d&rsquo;en assumer les cons\u00e9quences. Bref&#8230;[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb parallax_image=\u00a0\u00bb2531&Prime;][vc_column][vc_empty_space height=\u00a0\u00bb600px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"lipsum\">\n<p>Donc, plusieurs choix possibles en fonction de votre syst\u00e8me d&rsquo;\u00e9chappement. Avant tout, il faut savoir que votre silencieux qui repr\u00e9sente 90% des modifications faites sur une moto, est homologu\u00e9 d&rsquo;une certaine mani\u00e8re; avec ou sans chicane (99% avec, pour les nouvelles motos \u00e9quip\u00e9e de valves \u00e0 l&rsquo;\u00e9chappement en g\u00e9n\u00e9ral le silencieux de remplacement est exempt de chicane) avec ou sans catalyseur, ceci d\u00e9pend de l&rsquo;ann\u00e9e de votre moto.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag - Desktop -->\n            <ins data-revive-zoneid=\"55\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h4>Autant d&rsquo;\u00e9l\u00e9ments qui font que si vous en modifiez un seul, votre homologation CH, ne fera plus fois, je m&rsquo;explique :<\/h4>\n<p><em>&#8211;\u00a0Je viens d&rsquo;acheter un silencieux homologu\u00e9 CH et je d\u00e9cide de retirer ma chicane, car c&rsquo;est bien connu, le bruit me sauvera.<\/em> En fait, si on ne te voit pas, le gars dans sa voiture avec la sono \u00e0 fond, ne t&rsquo;endendra pas non plus hein, mais passons.<br \/>\nD\u00e9sol\u00e9 pour toi, mais en cas de contr\u00f4le, ton \u00e9chappement devient non conforme, ce qui engendrera une contravention. Il est \u00e9galement possible de se faire poursuivre pour \u00e9chappement bruyant.<\/p>\n<p><em>&#8211; Je viens d&rsquo;acheter un silencieux homologu\u00e9 CH et je d\u00e9cide de raccourcir ma chicane.<\/em><br \/>\nD\u00e9sol\u00e9 pour toi, mais en cas de contr\u00f4le, ton \u00e9chappement devient non conforme, ce qui engendrera une contravention.\u00a0Il est \u00e9galement possible de se faire poursuivre pour \u00e9chappement bruyant.<\/p>\n<p><em>&#8211; Toujours avec mon silencieux homologu\u00e9 CH, avec ma chicane, mais je me suis dit que j&rsquo;allais supprimer mon catalyseur, car je suis persuad\u00e9 de gagner au moins 10cv&#8230;<\/em><br \/>\nD\u00e9sol\u00e9 pour toi, mais l\u00e0 encore en cas de contr\u00f4le, ton \u00e9chappement devient non conforme, ce qui engendrera une contravention.\u00a0Il est \u00e9galement possible de se faire poursuivre pour \u00e9chappement bruyant.<\/p>\n<p><em>&#8211; Bon, je suis un rebelle et je monte un silencieux trouv\u00e9 sur Aliexpress, Wish&#8230;mais pour une autre moto que la mienne, car il est moins cher et je le trouve plus beau.\u00a0<\/em><br \/>\nD\u00e9sol\u00e9 pour toi, mais en cas de contr\u00f4le, ton \u00e9chappement devient non r\u00e9ceptionn\u00e9 pour votre moto, ce qui engendrera une contravention. Il est \u00e9galement possible de se faire poursuivre pour \u00e9chappement bruyant.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<div id=\"lipsum\">\n<p>Vous l&rsquo;aurez compris, d\u00e8s que vous touchez un seul \u00e9l\u00e9ment de votre silencieux homologu\u00e9 CH, ce dernier perd automatiquement sa validit\u00e9.<br \/>\nEt autant vous dire que les contraventions sont plut\u00f4t sal\u00e9es, puisque pour un seul code contraventionnel li\u00e9 \u00e0 un syst\u00e8me d&rsquo;\u00e9chappement non conforme ou non r\u00e9ceptionn\u00e9, vous devrez d\u00e9bourser entre CHF 400.- et 500.- (montant diff\u00e9rent suivant les cantons). Si \u00e0 ceci vient s&rsquo;ajouter le code pour \u00e9chappement bruyant, vous fr\u00f4lerez les 1&rsquo;000.-.<\/p>\n<p>Alors attention \u00e0 vous, les beaux jours reviennent et la Police ne manquera pas de vous rappeler \u00e0 l&rsquo;ordre au besoin.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Donc autant le dire, oui, les \u00e9chappements qui sont vendus en suisse avec certificat CH sont plus ch\u00e8res pour diverses raisons, dont les v\u00e9rifications par les autorit\u00e9s des certifcats Europ\u00e9en&#8230;, mais ils ont l&rsquo;avantage de vous permettre de rouler en toute l\u00e9galit\u00e9 et vous permettront d&rsquo;\u00e9viter des frais totalement inutiles.\u00a0<\/strong><\/p>\n<p>Nous tenons encore \u00e0 remercier nos diff\u00e9rents intervenants avec une mention particuli\u00e8re au canton du Jura qui aura pris le temps de nous d\u00e9livrer des r\u00e9ponses des plus compl\u00e8tes.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] S\u2019il y a bien un sujet qui revient continuellement sur les r\u00e9seaux sociaux, c\u2019est celui de l\u2019homologation des syst\u00e8mes d\u2019\u00e9chappements pour la Suisse. Car oui, la Suisse ne fait toujours pas partie de l\u2019Europe, enfin si, mais non, que g\u00e9ographiquement en fait, ce qui en fait une petite omerta avec ses propres r\u00e8gles en [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":2532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[240],"tags":[243,241,242],"class_list":["post-2511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutoriel","tag-controle-technique","tag-legal","tag-modification"],"_links":{"self":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/2511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/comments?post=2511"}],"version-history":[{"count":3,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/2511\/revisions"}],"predecessor-version":[{"id":2534,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/2511\/revisions\/2534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/media\/2532"}],"wp:attachment":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/media?parent=2511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/categories?post=2511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/tags?post=2511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}