{"id":18099,"date":"2024-11-19T23:24:22","date_gmt":"2024-11-19T22:24:22","guid":{"rendered":"https:\/\/acidmoto.ch\/site\/?p=18099"},"modified":"2024-11-20T08:10:35","modified_gmt":"2024-11-20T07:10:35","slug":"honda-nt1100-dct-electronic-suspensions-routiere-sans-concurrente","status":"publish","type":"post","link":"https:\/\/acidmoto.ch\/site\/honda-nt1100-dct-electronic-suspensions-routiere-sans-concurrente\/","title":{"rendered":"Honda NT1100 DCT Electronic Suspensions \u2013 Routi\u00e8re sans concurrente ?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h3>La NT 1100 est arriv\u00e9e sur le march\u00e9 fin 2021 en faisant revenir un genre de Deauville sur un march\u00e9 o\u00f9 les routi\u00e8res sont devenues rares. C&rsquo;est simple, en bicylindre en ligne c&rsquo;est la seule qui me vienne en t\u00eate. La Versys a 4 cylindres, la R 1250 RT c&rsquo;est un boxer, les autres bi sont des trails. Cette singularit\u00e9 fait-elle une excellente moto pour voyager ? Pr\u00e8s de 20 000 ont \u00e9t\u00e9 vendues, la nouvelle gagnera-t-elle des clients ?<\/h3>\n<p>[\/vc_column_text][vc_video link=\u00a0\u00bbhttps:\/\/youtu.be\/OcEMzeQsd9g\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][\/vc_column][\/vc_row][vc_row el_id=\u00a0\u00bbessai\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>ESSAI<\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Le nom de ce mod\u00e8le est simplement l&rsquo;abr\u00e9viation de <i>New Tourer<\/i>, il fallait quelque chose de simple et \u00e9vocateur pour ce concept d&rsquo;une moto qui partage son ch\u00e2ssis et son moteur avec l&rsquo;Africa Twin, mais pas son march\u00e9. Les utilisateurs 100% routiers d&rsquo;Africa Twin ne sont pas rares, seulement la forme de ce mod\u00e8le peut dissuader les pilotes plus petits, bien que <a href=\"https:\/\/acidmoto.ch\/site\/roadtrip-en-africa-twin-adventure-sport-1100-avec-boite-dct-de-2024\/\" target=\"_blank\" rel=\"noopener\">Nida a prouv\u00e9 d&rsquo;elle est facile \u00e0 prendre en main<\/a>. Alors la NT se pr\u00e9sente l\u00e0, plus basse, plus touring, taill\u00e9e pour rouler longtemps mais exclusivement sur route.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag -->\n            <ins data-revive-zoneid=\"54\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]En 2025, elle reste fondamentalement la m\u00eame, tout en profitant d&rsquo;am\u00e9liorations significatives d\u00e9j\u00e0 vue sur la derni\u00e8re Africa Twin Adventure Sport. La boite DCT se comporte de fa\u00e7on toujours plus naturelle, on gagne en s\u00e9curit\u00e9 gr\u00e2ce \u00e0 l&rsquo;IMU n\u00e9cessaire \u00e0 l&rsquo;ABS sur l&rsquo;angle et \u00e0 un contr\u00f4le de traction plus pr\u00e9cis, un rafra\u00eechissement du coup de crayon la distingue visuellement du premier mod\u00e8le.[\/vc_column_text][vc_masonry_media_grid css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509422-9016c095-a521-6&Prime; include=\u00a0\u00bb18133,18135,18140&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Les feux avant int\u00e8grent les clignotants \u00e0 l&rsquo;int\u00e9rieur de son \u00e9clairage de jour, il n&rsquo;y a plus d&rsquo;excroissances pour servir d&rsquo;indicateurs de direction. Autour de ces phares, des traits d&rsquo;expressions cassent le look trop rond et lisse de la premi\u00e8re version. Elle reste tr\u00e8s apparent\u00e9e au X-ADV donc on a envie de dire que la NT a un air de scooter, mais c&rsquo;est un air de Honda qui se retrouve sur plusieurs mod\u00e8les. De chaque c\u00f4t\u00e9 du r\u00e9servoir, les habillages pr\u00e9sentent le nom du mod\u00e8le pour renforcer un peu son identit\u00e9. Avec le logo Honda argent\u00e9 sur le rond rouge, l&rsquo;apanage des mod\u00e8les plus premium de la marque.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid element_width=\u00a0\u00bb6&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509424-3fd2413c-37e2-4&Prime; include=\u00a0\u00bb18158,18136&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">J&rsquo;ai gard\u00e9 un tr\u00e8s bon souvenir de la <a href=\"https:\/\/acidmoto.ch\/site\/honda-crf1100-africa-twin-adventure-sport-en-manuelle-et-dct-mais-surtout-en-19\/\" target=\"_blank\" rel=\"noopener\">derni\u00e8re it\u00e9ration de l&rsquo;Africa Twin en janvier 2024<\/a>. Transmission DCT sur S2 avec le mode de conduite le plus dynamique, elle se comporte admirablement bien sur la route et permet de faire un tour en tout terrain. Je suis pass\u00e9 \u00e0 cot\u00e9 de la NT par contre, c&rsquo;est donc une d\u00e9couverte et ne pourrai faire aucune comparaison directe. En plus, Honda m&rsquo;a r\u00e9serv\u00e9 une NT avec le pack le plus fourni d&rsquo;accessoires : feux additionnels, selle confort \u00e0 surpiq\u00fbres rouges, top case avec dosseret moelleux, sacoche de r\u00e9servoir magn\u00e9tique, rien ne manque. Les valises sont d&rsquo;office sur les NT 1100 depuis sa sortie, elles ont juste gagn\u00e9 25 mm de profondeur sur la nouvelle pour accueillir un casque int\u00e9gral. Elles se fixent aux m\u00eames points, rien n&#8217;emp\u00eache d&rsquo;en acheter pour sa NT &rsquo;21-&rsquo;24 et augmenter son volume de chargement.<\/p>\n<p>[\/vc_column_text][vc_single_image image=\u00a0\u00bb18160&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bblink_image\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Ma moto d&rsquo;essai est bleue, une couleur qu&rsquo;il y avait d\u00e9j\u00e0 au catalogue pr\u00e9c\u00e9demment avec le noir. M\u00eame dans cette teinte, elle met un coup de vieux \u00e0 la premi\u00e8re version trop lisse. Avec des car\u00e9nages plus structur\u00e9s et des embl\u00e8mes NT 1100 en relief, elle a bien plus de caract\u00e8re. On ne le remarque pas imm\u00e9diatement, mais les clignotants sont \u00e0 l&rsquo;int\u00e9rieur des feux, comme sur les voitures. Par cons\u00e9quent, il n&rsquo;y a rien qui d\u00e9passe et c&rsquo;est prometteur pour de futurs mod\u00e8les. La nouvelle couleur Matt Warm Ash Metallic, une teinte sable tr\u00e8s claire, fait bonne impression alors que le blanc et le rouge sont abandonn\u00e9s.<\/p>\n<p>[\/vc_column_text][vc_masonry_media_grid element_width=\u00a0\u00bb12&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509424-e4494972-6459-3&Prime; include=\u00a0\u00bb18132&Prime;][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag -->\n            <ins data-revive-zoneid=\"56\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Qui le souhaite peut encore acheter sa NT 1100 avec une transmission manuelle, par contre pour avoir la suspension \u00e9lectronique, il faut obligatoirement prendre la DCT avec. La proportion de vente de cette transmission \u00e0 double embrayage est telle, que Honda s&rsquo;est \u00e9pargn\u00e9 le d\u00e9veloppement de la suspension semi-active pour une manuelle. La DCT en suspensions traditionnelles existe aussi pour un prix interm\u00e9diaire. Lors de l&rsquo;essai, on s&rsquo;est focalis\u00e9 sur la plus \u00e9quip\u00e9e, qu&rsquo;on reconna\u00eet d&rsquo;ailleurs aux fourreaux de fourche anodis\u00e9s bronze.<\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">La NT 1100 reste une moto \u00e9quip\u00e9e d&rsquo;une cl\u00e9 traditionnelle, la SmartKey de la CBR 1000 par exemple, reste au placard pour des raisons de co\u00fbts d&rsquo;installation sur un mod\u00e8le existant. En plus, il y a le verrouillage des valises qu&rsquo;il aurait fallu repenser s&rsquo;il y avait un transpondeur au fond d&rsquo;une poche.<\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<div id=\"lipsum\">\n<p class=\"p1\">Ce qui attire la curiosit\u00e9 des essayeurs, c&rsquo;est la nouvelle protection au vent, mont\u00e9e sur un rail pour une d\u00e9placement de 176 mm et utilisable de la seule main gauche. Celle-ci doit consid\u00e9rablement am\u00e9liorer le confort sur long trajet.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]Son mouvement perfectionn\u00e9 augmente l&rsquo;inclinaison de la vitre \u00e0 mesure qu&rsquo;on la monte. J&rsquo;attendrai de faire des axes tr\u00e8s roulants pour tester les 5 positions possibles et surtout la manipulation.[\/vc_column_text][vc_masonry_media_grid element_width=\u00a0\u00bb6&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509425-d43e176c-8dda-7&Prime; include=\u00a0\u00bb18154,18153&Prime;][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb parallax_image=\u00a0\u00bb18173&Prime; el_id=\u00a0\u00bbImage Parallaxe\u00a0\u00bb][vc_column parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb800px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Le moteur de cette Honda est le m\u00eame que dans l&rsquo;<a href=\"https:\/\/acidmoto.ch\/site\/honda-crf1100-africa-twin-adventure-sport-en-manuelle-et-dct-mais-surtout-en-19\/\" target=\"_blank\" rel=\"noopener\">Africa Twin test\u00e9e en janvier 2024<\/a>, modifications de bielles et de pistons comprises. La courbe de couple a g\u00e9n\u00e9reusement grimp\u00e9 dans les mi-r\u00e9gimes, ce qui apporte beaucoup d&rsquo;agr\u00e9ment de conduite car on est presque tout le temps sur cette zone. Lors de cet essai justement, j&rsquo;avais tir\u00e9 un trait sur le mode D de la transmission, commen\u00e7ons directement en S2, ce qui \u00e9tait le meilleur mode. Quant au riding mode, il faut conna\u00eetre la diff\u00e9rence entre Tour, Urban et Rain. Le premier d\u00e9livre toute la puissance avec peu de frein moteur et une suspension faite pour une conduite dynamique. Urban puissance et frein moteur sont interm\u00e9diaires, suspension au comportement tr\u00e8s proche de suspension m\u00e9canique. Le dernier pour les conditions pr\u00e9caires r\u00e9duit significativement la puissance et la suspension devient tr\u00e8s souple.<\/p>\n<p>[\/vc_column_text][vc_masonry_media_grid css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509425-6cd19294-0d44-0&Prime; include=\u00a0\u00bb18163,18164,18165&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<div id=\"lipsum\">\n<p class=\"p1\">Je d\u00e9bute l&rsquo;essai en Urban et S2, je reconnais vite l&rsquo;onctuosit\u00e9 du bicylindre. G\u00e9n\u00e9reux en couple, r\u00e9actif. Bien que cette architecture moteur ne soit pas la premi\u00e8re \u00e0 laquelle on pense pour une routi\u00e8re, elle s&rsquo;y pr\u00eate finalement assez bien. Sur les longues acc\u00e9l\u00e9rations, je regrette qu&rsquo;il n&rsquo;y ait pas plus d&rsquo;allonge, mais comme je laisse faire la transmission c&rsquo;est bien \u00e9gal de monter deux rapports o\u00f9 un 4 cylindres n&rsquo;en changeait peut-\u00eatre pas. L&rsquo;amortissement est convenable, montrant ses limites quand je conserve un maximum de vitesse en courbe, normal c&rsquo;est un r\u00e9glage interm\u00e9diaire. L&rsquo;occasion de passer en mode Tour se pr\u00e9sente rapidement, juste avec les fl\u00e8ches haut\/bas on change \u00e7a sans autre proc\u00e9dure. La r\u00e9ponse du moteur plus nerveuse correspond mieux \u00e0 la conduite dynamique, voyons si la suspension suit.<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid element_width=\u00a0\u00bb6&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509426-90def7bd-eaf4-8&Prime; include=\u00a0\u00bb18166,18167&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">La reprogrammation de la boite DCT est assez facile \u00e0 identifier, d\u00e9j\u00e0 \u00e0 basse vitesse le ressenti est plus naturel. Je m&rsquo;imagine parfaitement faire des exercices de plateau avec, sans aucune chance de caler. Sur la route aussi je note des changements de comportement gr\u00e2ce aux informations d&rsquo;angle et d&rsquo;acc\u00e9l\u00e9ration angulaire qui influencent la transmission. Avant on pouvait avoir des r\u00e9trogradages en phase de freinage, parce que la vitesse de d\u00e9placement demandait logiquement le rapport inf\u00e9rieur. Maintenant lorsqu&rsquo;on freine, la moto pitch vers l&rsquo;avant, la boite le sait et garde le rapport engag\u00e9 jusqu&rsquo;\u00e0 ce que la fourche remonte. C&rsquo;est l&rsquo;instant o\u00f9 on inscrit ensuite la moto dans une courbe et le changement de vitesse se fait \u00e0 ce moment l\u00e0. Le freinage est plus constant, r\u00e9gulier, pas d\u00e9stabilis\u00e9 par le travail de la DCT.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_masonry_media_grid css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509426-015fc2e7-94d8-2&Prime; include=\u00a0\u00bb18156,18155,18151&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Alors que j&rsquo;adorais S2, la NT est un peu flemmarde lors des relances. Si on ne soude pas les gaz en but\u00e9e, elle essaye souvent de conserver son rapport, m\u00eame en mont\u00e9e. Il y a au ressenti 3 zones dans la course de la poign\u00e9e de gaz, alors que je n&rsquo;avais pas remarqu\u00e9 \u00e7a sur l&rsquo;Africa Twin. Je me sers du bouton pour faire un kickdown et avoir la relance que je souhaite. Une longue pression sur le mode S pour changer en S3, l\u00e0 aussi c&rsquo;est tr\u00e8s rapide et pas compliqu\u00e9. Les sollicitations sont mieux interpr\u00e9t\u00e9es et les relances dynamiques. Le point n\u00e9gatif, on reste plus longtemps sur le rapport engag\u00e9, m\u00eame si on a rel\u00e2ch\u00e9 la poign\u00e9e. Il faut forcer la vitesse suivant manuellement. Au finale les deux param\u00e8tres demandent \u00e0 mon sens une intervention humaine pour \u00eatre irr\u00e9prochables. Pourquoi je n&rsquo;avais pas cette impression en janvier sur l&rsquo;Africa Twin ?<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb content_placement=\u00a0\u00bbtop\u00a0\u00bb parallax=\u00a0\u00bbcontent-moving\u00a0\u00bb parallax_image=\u00a0\u00bb18177&Prime;][vc_column][vc_empty_space height=\u00a0\u00bb800px\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">J&rsquo;ai envie d&rsquo;essayer un mode de pilotage personnalis\u00e9, o\u00f9 je peux choisir la suspension avec puissance maximale et frein moteur minimum. Oblig\u00e9 de le faire \u00e0 l&rsquo;arr\u00eat car on entre dans le menu en touchant l&rsquo;heure \u00e0 l&rsquo;\u00e9cran. Toutes fonctions tactiles sont d\u00e9sactiv\u00e9es en roulant. La navigation fonctionne avec les doigts \u00e0 l&rsquo;\u00e9cran ou avec les boutons du commodo gauche. La r\u00e9activit\u00e9 de l&rsquo;\u00e9cran laisse \u00e0 d\u00e9sirer mais fonctionne peu importe les gants qu&rsquo;on porte. Une fois dans USER1, il faut encore savoir que Power 1 est la puissance maximale, EBC 1 est le frein moteur minimal. Et pour la suspension, on choisi le mode de base, puis affine sa pr\u00e9f\u00e9rence pour l&rsquo;avant et l&rsquo;arri\u00e8re, puis on r\u00e8gle individuellement la pr\u00e9charge des 4 options accessibles en roulant (solo, duo, solo avec bagages et duo avec bagages). Les possibilit\u00e9s sont nombreuses, si on comprend ce qu&rsquo;on fait on peut certainement atteindre un r\u00e9glage tr\u00e8s personnalis\u00e9 optimal pour son usage. Mais il faut avouer que s&rsquo;arr\u00eater \u00e0 chaque fois ne facilite pas la recherche.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_masonry_media_grid element_width=\u00a0\u00bb12&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509427-b2af781f-fccf-2&Prime; include=\u00a0\u00bb18150&Prime;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Je note aussi qu&rsquo;en roulant, les commodo sont pas mal tourn\u00e9s vers le bas, j&rsquo;aurais aim\u00e9 les redresser pour voir o\u00f9 j&rsquo;ai mon pouce et m&rsquo;\u00e9viter de klaxonner ou r\u00e9trograder \u00e0 la place de mettre un clignotant. Il y a trop de boutons au m\u00eame endroit. Quelque part, heureusement que le r\u00e9gulateur de vitesse est \u00e0 droite m\u00eame si ce n&rsquo;est pas tr\u00e8s habituel. Le bouton fonction \u00e0 droite et le +\/- d\u00e9di\u00e9 \u00e0 gauche sont bien utiles pour les poign\u00e9es chauffantes ou les feux additionnelles, mais ce sont encore plus de boutons \u00e0 conna\u00eetre.<\/p>\n<p>[\/vc_column_text][vc_masonry_media_grid css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509427-def091a0-22b1-4&Prime; include=\u00a0\u00bb18149,18148,18147&Prime;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Petite parenth\u00e8se sur Car Play, Android Auto. Ne fonctionne qu&rsquo;avec un cable USB et pour avoir du son il faut coupler le headset au t\u00e9l\u00e9phone. Si on utilise son t\u00e9l\u00e9phone coupl\u00e9 en bluetooth \u00e0 la moto, pour entendre la conversation ou la musique, le headset doit \u00eatre li\u00e9 \u00e0 la moto. Comme quoi, \u00e9couter son vendeur quand on r\u00e9ceptionne la moto est important.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime;][vc_masonry_media_grid element_width=\u00a0\u00bb12&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509428-352b331e-e9a0-7&Prime; include=\u00a0\u00bb18145&Prime;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Parlons de cette protection saute vent, la vitre principale et ses deux d\u00e9flecteurs lat\u00e9raux. Ces deux la sont tr\u00e8s efficaces, bien que paraissent fragiles quand ils bougent avec le vent. Main, avant-bras et \u00e9paule sont prot\u00e9g\u00e9s. Honda a pr\u00e9f\u00e9r\u00e9 cette solution \u00e0 des prot\u00e8ges-main au guidon qui rendait la direction plus lourde. Monter le saute-vent en roulant est possible, s&rsquo;il est en position basse c&rsquo;est quand m\u00eame compliqu\u00e9 d&rsquo;aller chercher la molette loin en avant \u00e0 gauche et ensuite monter l&rsquo;ensemble. Sur l&#8217;emplacement le plus haut, le plexi est presque vertical et des remous d\u00e9sagr\u00e9ables apparaissent sur le casque. Au del\u00e0 de 110 km\/h,<span class=\"Apple-converted-space\">\u00a0 <\/span>c&rsquo;est si pr\u00e9sent que j&rsquo;en ai eu la vision troubl\u00e9e. Idem en position 4\/5, des coups de vent r\u00e9p\u00e9t\u00e9s \u00e0 bonne fr\u00e9quence forcent vite \u00e0 baisser encore d&rsquo;un cran.<\/p>\n<p>[\/vc_column_text][vc_masonry_media_grid css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509428-a3669d7b-20ca-0&Prime; include=\u00a0\u00bb18168,18169,18170&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Dans cette position, le saute-vent a une inclinaison a\u00e9rodynamique et me prot\u00e8ge suffisamment. Le courant d&rsquo;air me passe par dessus le casque et mes bras sont d\u00e9j\u00e0 prot\u00e9g\u00e9s. J&rsquo;ai le plus rouler avec cette configuration car c&rsquo;\u00e9tait la plus agr\u00e9able. Dommage d&rsquo;avoir cr\u00e9\u00e9 une protection au vent qui puisse monter si haut et ne serve finalement pas.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">J&rsquo;ai aussi compar\u00e9 l&rsquo;assise avec la selle de s\u00e9rie. Parce que celle-ci me semblait plus horizontale, avec le bassin plus tourn\u00e9 vers l&rsquo;avant, j&rsquo;ai pr\u00e9f\u00e9r\u00e9 cette version. L&rsquo;autre est plus douce pour le fessier, mais je m&rsquo;enfonce peut-\u00eatre un rien de trop ce qui la rendait moins confortable. C&rsquo;est surtout une question de go\u00fbt personnel et de posture, seul un essai dira s&rsquo;il en est de m\u00eame pour vous.<\/p>\n<p>[\/vc_column_text][vc_masonry_media_grid element_width=\u00a0\u00bb3&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509428-01f1f215-5c8d-1&Prime; include=\u00a0\u00bb18174,18175,18178,18171&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">Mon avis sur cette moto est finalement tr\u00e8s affect\u00e9 par seulement deux d\u00e9tails : ce comportement de boite DCT entre S2 et S3 qui n&rsquo;existe pas et cette protection au vent si prometteuse au d\u00e9part qui est d\u00e9ceptive sans \u00eatre inefficace. Je pourrais aussi disserter sur le commodo gauche, mais celui-ci doit bien s&rsquo;apprivoiser avec le temps. La suspension active apporte un plus \u00e0 la moto, pour celui qui cherche un bonus de polyvalence dans cette routi\u00e8re. Le fait qu&rsquo;elle existe toujours en manuelle s\u00e9duira aussi un public en recherche de \u00e7a. Enfin je peux en attester : un bicylindre en ligne peut aussi animer une routi\u00e8re, ce n&rsquo;est pas r\u00e9dhibitoire.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p class=\"p1\">La NT 1100 va prochainement \u00eatre livr\u00e9e aux revendeurs Honda, les prix ont \u00e9t\u00e9 d\u00e9finis comme suit:<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\">manuelle CHF 14&rsquo;650.-<\/li>\n<li class=\"li1\">DCT CHF 15&rsquo;490.-<\/li>\n<li class=\"li1\">DCT Electronic Suspension CHF 16&rsquo;390.-<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h4><span lang=\"FR-CH\"><strong>Urban pack<\/strong><\/span><\/h4>\n<p><span lang=\"FR-CH\">Top-case coordonn\u00e9 50 l avec sac int\u00e9rieur et dosseret passager<\/span><\/p>\n<h4><strong><span lang=\"FR-CH\">Voyage pack<\/span><\/strong><\/h4>\n<ul>\n<li><span lang=\"FR-CH\">Top-case coordonn\u00e9 50 l avec sac int\u00e9rieur et dosseret passager<\/span><\/li>\n<li><span lang=\"FR-CH\">Sacoche r\u00e9servoir 4,5 l<\/span><\/li>\n<li><span lang=\"FR-CH\">Selle confort pour pilote et passager<\/span><\/li>\n<li><span lang=\"FR-CH\">Repose-pieds confort pour pilote<\/span><\/li>\n<li><span lang=\"FR-CH\">Feux antibrouillards<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"my-hello-element\"><!-- Revive Adserver Asynchronous JS Tag - Desktop -->\n            <ins data-revive-zoneid=\"55\" data-revive-id=\"4d5449d616ecffc89ec43465d94db3b9\"><\/ins>\n            <script async src=\"\/\/adserver.acidmoto.ch\/www\/delivery\/asyncjs.php\"><\/script><\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row el_id=\u00a0\u00bbgal\u00a0\u00bb][vc_column][vc_empty_space height=\u00a0\u00bb60px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>GALERIE<\/h2>\n<p>[\/vc_column_text][vc_masonry_media_grid style=\u00a0\u00bbload-more\u00a0\u00bb items_per_page=\u00a0\u00bb12&Prime; element_width=\u00a0\u00bb2&Prime; css=\u00a0\u00bb\u00a0\u00bb grid_id=\u00a0\u00bbvc_gid:1732055509429-e6dc219e-101d-2&Prime; include=\u00a0\u00bb18132,18133,18134,18135,18136,18137,18138,18139,18140,18141,18142,18143,18144,18145,18146,18147,18148,18149,18150,18151,18152,18153,18154,18155,18156,18157,18158,18159,18160,18161,18162,18163,18164,18165,18166,18167,18168,18169,18170,18171,18172,18173,18174,18175,18176,18177,18178&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb] La NT 1100 est arriv\u00e9e sur le march\u00e9 fin 2021 en faisant revenir un genre de Deauville sur un march\u00e9 o\u00f9 les routi\u00e8res sont devenues rares. C&rsquo;est simple, en bicylindre en ligne c&rsquo;est la seule qui me vienne en t\u00eate. La Versys a 4 cylindres, la R 1250 RT c&rsquo;est un boxer, les [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17,152,209],"tags":[588,732],"class_list":["post-18099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-essais","category-routiere","category-video","tag-588","tag-dct","xg_marques-honda"],"_links":{"self":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/18099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/comments?post=18099"}],"version-history":[{"count":13,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/18099\/revisions"}],"predecessor-version":[{"id":18188,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/posts\/18099\/revisions\/18188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/media\/18172"}],"wp:attachment":[{"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/media?parent=18099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/categories?post=18099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acidmoto.ch\/site\/wp-json\/wp\/v2\/tags?post=18099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}